{"id":825,"date":"2022-10-05T12:37:33","date_gmt":"2022-10-05T15:37:33","guid":{"rendered":"https:\/\/radio1.webunitystudio.site\/bolsonaro-recebe-apoio-do-governador-reeleito-do-distrito-federal-agencia-brasil\/"},"modified":"2022-10-05T12:37:33","modified_gmt":"2022-10-05T15:37:33","slug":"bolsonaro-recebe-apoio-do-governador-reeleito-do-distrito-federal-agencia-brasil","status":"publish","type":"post","link":"https:\/\/webradio2.dimariostreamhost.com\/site\/bolsonaro-recebe-apoio-do-governador-reeleito-do-distrito-federal-agencia-brasil\/","title":{"rendered":"Bolsonaro recebe apoio do governador reeleito do Distrito Federal &#8211; Ag\u00eancia Brasil"},"content":{"rendered":"<p><strong>Ex.<\/strong>Sa\u00fade, Presidente, Governo <br \/>O governador reeleito do Distrito Federal, Ibaneis Rocha, declarou hoje (5) apoio \u00e0 candidatura \u00e0 reelei\u00e7\u00e3o de Jair Bolsonaro (PL) para a Presid\u00eancia. Os dois se reuniram na manh\u00e3 desta quarta-feira no Pal\u00e1cio da Alvorada, em Bras\u00edlia.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1486446&amp;o=node\" style=\"width:1px;height:1px\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1486446&amp;o=node\" style=\"width:1px;height:1px\" \/><br \/>\u201cO Distrito Federal \u00e9 hospedeiro dos principais poderes, ent\u00e3o essa harmonia, desde o in\u00edcio, foi o que n\u00f3s buscamos&#8221;. Durante o an\u00fancio de apoio, Iban\u00eas citou a import\u00e2ncia do governo federal na realiza\u00e7\u00e3o de obras no DF, que tem &#8220;depend\u00eancia muito forte&#8221; do Fundo Constitucional.<br \/>A institui\u00e7\u00e3o do Fundo Constitucional do DF est\u00e1 prevista na Constitui\u00e7\u00e3o e os recursos, corrigidos anualmente, s\u00e3o usados para custear a organiza\u00e7\u00e3o e a manuten\u00e7\u00e3o das for\u00e7as de seguran\u00e7a p\u00fablica, bem como assist\u00eancia financeira para servi\u00e7os p\u00fablicos de sa\u00fade e educa\u00e7\u00e3o. Em 2022, a previs\u00e3o do or\u00e7amento do fundo \u00e9 de R$ 16,28 bilh\u00f5es.<br \/>No primeiro turno das elei\u00e7\u00f5es, o candidato Bolsonaro obteve 51,65% dos votos v\u00e1lidos no Distrito Federal. Luiz In\u00e1cio Lula da Silva ficou com 36,85% de prefer\u00eancia do eleitorado da capital.<br \/>Segundo Bolsonaro, essa harmonia entre os poderes e entes da federa\u00e7\u00e3o \u00e9 importante para a governabilidade. \u201cNada melhor para um Presidente da Rep\u00fablica do que ter um governador amigo ao seu lado. Todos ganham, em especial a governabilidade\u201d, disse.<br \/>\u201cHoje, voc\u00eas podem ver o perfil dos novos ou reeleitos parlamentares na C\u00e2mara e no Senado, um perfil mais conservador, mais fam\u00edlia, um perfil mais liberdade econ\u00f4mica. Ou seja, est\u00e1 tudo pavimentado para que a harmonia seja completa entre Executivo e Legislativo, para o bem do nosso querido Brasil\u201d, completou Bolsonaro.<br \/>                                                 Edi\u00e7\u00e3o:   Denise Griesinger                    <br \/>Esquema serve aos interesses do crime organizado, como fac\u00e7\u00f5es, contrabandistas de produtos importados e qualquer um que necessite enviar valores il\u00edcitos ao exterior.<br \/>&#8220;Nossa candidatura n\u00e3o \u00e9 mais uma candidatura ib\u00e9rica, \u00e9 uma candidatura europeia&#8221;, disse Luis Rubiales, presidente da RFE. Decis\u00e3o foi confirmada por dirigente da Federa\u00e7\u00e3o Portuguesa.<br \/>Ibaneis Rocha esteve no Pal\u00e1cio da Alvorada, na manh\u00e3 de hoje. Presidente citou a governabilidade ao agradecer o apoio do governador reeleito do DF.<br \/>A social-democrata Mette Frederiksen antecipou a realiza\u00e7\u00e3o das elei\u00e7\u00f5es em sete meses, para 1\u00b0 de novembro. Ela garantiu que se vencer, formar\u00e1 um governo amplo.<br \/>Ag\u00eancia Tass informou que chefe da Ag\u00eancia Internacional de Energia At\u00f4mica, Rafael Grossi, visitar\u00e1 Moscou nos pr\u00f3ximos dias para discutir situa\u00e7\u00e3o na usina.<br \/>A\u00e7\u00e3o faz parte de inqu\u00e9rito que apura exporta\u00e7\u00e3o de 320 quilos de coca\u00edna para Portugal, no fim de junho. Na ocasi\u00e3o, tr\u00eas brasileiros foram presos em flagrante por tr\u00e1fico.<br \/>A ind\u00fastria tamb\u00e9m registra quedas de 0,1% na m\u00e9dia m\u00f3vel trimestral de 1,3% no acumulado do ano e de 2,7% em 12 meses.<br \/>Indicador acumula alta de 8,8 pontos nos \u00faltimos seis meses. Em setembro, quatro dos sete componentes tiveram alta, com destaque para tend\u00eancia dos neg\u00f3cios da ind\u00fastria.<br \/>Iranianos em todo o pa\u00eds participam de manifesta\u00e7\u00f5es pela morte de Masha Amini, de 22 anos, que morreu sob cust\u00f3dia da pol\u00edcia da moral.<br \/>Bolsonaro e Lula continuam campanha para disputa do segundo turno, nesta quarta-feira.<br \/>Conhe\u00e7a nossos aplicativos nas lojas online da iTunes e Google<\/p>\n<p><a href=\"https:\/\/agenciabrasil.ebc.com.br\/politica\/noticia\/2022-10\/bolsonaro-recebe-apoio-do-governador-reeleito-do-distrito-federal\">source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ex.Sa\u00fade, Presidente, Governo O governador reeleito do Distrito Federal, Ibaneis Rocha, declarou hoje (5) apoio \u00e0 candidatura \u00e0 reelei\u00e7\u00e3o de Jair Bolsonaro (PL) para a Presid\u00eancia. Os dois se reuniram na manh\u00e3 desta quarta-feira no Pal\u00e1cio da Alvorada, em Bras\u00edlia.\u201cO Distrito Federal \u00e9 hospedeiro dos principais poderes, ent\u00e3o essa harmonia, desde o in\u00edcio, foi o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":826,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/825"}],"collection":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/comments?post=825"}],"version-history":[{"count":0,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/825\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media\/826"}],"wp:attachment":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media?parent=825"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/categories?post=825"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/tags?post=825"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}