{"id":833,"date":"2022-10-06T23:36:53","date_gmt":"2022-10-07T02:36:53","guid":{"rendered":"https:\/\/radio1.webunitystudio.site\/raphinha-elege-tres-grandes-rivais-do-brasil-na-copa-e-promete-seguir-dancando-eles-podem-falar-o-que-quiserem-espn-com-br\/"},"modified":"2022-10-06T23:36:53","modified_gmt":"2022-10-07T02:36:53","slug":"raphinha-elege-tres-grandes-rivais-do-brasil-na-copa-e-promete-seguir-dancando-eles-podem-falar-o-que-quiserem-espn-com-br","status":"publish","type":"post","link":"https:\/\/webradio2.dimariostreamhost.com\/site\/raphinha-elege-tres-grandes-rivais-do-brasil-na-copa-e-promete-seguir-dancando-eles-podem-falar-o-que-quiserem-espn-com-br\/","title":{"rendered":"Raphinha elege tr\u00eas grandes rivais do Brasil na Copa e promete seguir dan\u00e7ando: &#039;Eles podem falar o que quiserem&#039; &#8211; ESPN.com.br"},"content":{"rendered":"<p>Voc\u00ea est\u00e1 na Edi\u00e7\u00e3o Brasil. Para acessar edi\u00e7\u00f5es de outras regi\u00f5es, clique aqui.<br \/>Faltando pouco mais de dois meses para a estreia do <a href=\"\/futebol\/time\/_\/id\/205\"><strong>Brasil <\/strong><\/a>na <a href=\"\/futebol\/liga\/_\/nome\/fifa.world\"><strong>Copa do Mundo <\/strong><\/a>de <strong>2022<\/strong> no <strong>Qatar<\/strong>, contra a<strong> <a href=\"\/futebol\/time\/_\/id\/6757\/serbia\">S\u00e9rvia<\/a><\/strong>, no dia<strong> 24 de novembro<\/strong>, em Lusail, o atacante <strong>Raphinha <\/strong>elegeu os tr\u00eas principais rivais da <em>Amarelinha<\/em> na briga pelo t\u00edtulo.<br \/>Nesta quinta-feira (22), em Le Havre, na<strong> <\/strong>Fran\u00e7a, onde a sele\u00e7\u00e3o disputar\u00e1 amistoso contra <strong><a href=\"\/futebol\/time\/_\/id\/4469\/gana\">Gana<\/a><\/strong>, nesta sexta (23), o jogador do<a href=\"\/futebol\/time\/_\/id\/83\/barcelona\"> <strong>Barcelona<\/strong><\/a> colocou a atual campe\u00e3 mundial, <a href=\"\/futebol\/time\/_\/id\/478\/franca\"><strong>Fran\u00e7a<\/strong><\/a>, al\u00e9m de <a href=\"\/futebol\/time\/_\/id\/164\/espanha\"><strong>Espanha<\/strong><\/a> e<a href=\"\/futebol\/time\/_\/id\/448\/inglaterra\"><strong> Inglaterra<\/strong><\/a> entre as favoritas, ao lado do Brasil, para a conquista.<br \/><a href=\"https:\/\/www.starplus.com\/pt-br\/welcome\/combo-plus?cid=DTCI_STAR-Synergy-ESPN-Site-Onboarding-StarPlus-BR-StarPlus-NA-PTBR-NA-inlinecomboplus-NA\"><br \/>Al\u00e9m de todo o conte\u00fado ESPN, com o Combo+ voc\u00ea tem acesso ao melhor do entretenimento de Star+ e \u00e0s franquias mais amadas de Disney+. <b>Assine j\u00e1!<\/b><br \/><\/a><br \/>&#8220;Eu acredito que n\u00e3o s\u00f3 pela quest\u00e3o do ataque, mas o conjunto todo. <strong>S\u00e3o grandes sele\u00e7\u00f5es, para mim s\u00e3o as sele\u00e7\u00f5es da Espanha e da Inglaterra, que est\u00e3o bem preparadas para a Copa do Mundo, at\u00e9 mesmo a sele\u00e7\u00e3o francesa, eles v\u00e3o chegar bem preparados, s\u00e3o favoritos assim como o Brasil<\/strong>, mas a gente procura n\u00e3o s\u00f3 com a nossa qualidade, mas com o nosso comprometimento no trabalho chegarmos bem preparados&#8221;, disse, na zona mista.<br \/>Al\u00e9m de apontar as sele\u00e7\u00f5es favoritas \u00e0 conquista, Raphinha tamb\u00e9m falou sobre outro tema que vem dando o que falar nos \u00faltimos dias, <strong><a href=\"\/futebol\/real-madrid\/artigo\/_\/id\/10941353\/presidente-associacao-empresarios-espanha-usa-termo-racista-ataque-vinicius-jr\">ap\u00f3s o caso de racismo envolvendo Vinicius Jr., do Real Madrid<\/a><\/strong>: as dan\u00e7as durante a comemora\u00e7\u00e3o dos gols. E o atacante do <em>Bar\u00e7a<\/em> deixou claro que n\u00e3o abrir\u00e1 m\u00e3o de dan\u00e7ar.<br \/>&#8220;N\u00e3o acho que comemorar dan\u00e7ando \u00e9 falta de respeito. Falta de respeito \u00e9 ir na torcida advers\u00e1ria, xingar, fazer gestos. A partir do momento que voc\u00ea faz um gol, no melhor momento do futebol, tu vai comemorar da maneira que acha certo, que se sente feliz. E o brasileiro tem isso de dan\u00e7ar, de ser feliz, de se divertir. <strong>A gente n\u00e3o vai perder isso nunca. Eles podem falar o que quiserem, a gente vai continuar dan\u00e7ando<\/strong>&#8220;, finalizou.<br \/>Ap\u00f3s o amistoso contra Gana, o Brasil ainda volta a campo na pr\u00f3xima ter\u00e7a-feira (27), no Parque dos Pr\u00edncipes, em Paris, para mais um compromisso, desta vez contra a <strong><a href=\"\/futebol\/time\/_\/id\/659\/tunisia\">Tun\u00edsia<\/a><\/strong>, o \u00faltimo antes da estreia no Mundial.<\/p>\n<p><a href=\"https:\/\/www.espn.com.br\/futebol\/copa-do-mundo\/artigo\/_\/id\/10971150\/raphinha-elege-tres-grandes-rivais-brasil-copa-promete-seguir-dancando-eles-podem-falar-o-que-quiserem\">source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea est\u00e1 na Edi\u00e7\u00e3o Brasil. Para acessar edi\u00e7\u00f5es de outras regi\u00f5es, clique aqui.Faltando pouco mais de dois meses para a estreia do Brasil na Copa do Mundo de 2022 no Qatar, contra a S\u00e9rvia, no dia 24 de novembro, em Lusail, o atacante Raphinha elegeu os tr\u00eas principais rivais da Amarelinha na briga pelo t\u00edtulo.Nesta [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":834,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/833"}],"collection":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/comments?post=833"}],"version-history":[{"count":0,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/833\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media\/834"}],"wp:attachment":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media?parent=833"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/categories?post=833"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/tags?post=833"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}