{"id":867,"date":"2022-10-10T01:07:09","date_gmt":"2022-10-10T04:07:09","guid":{"rendered":"https:\/\/radio1.webunitystudio.site\/auxilio-brasil-pode-mudar-de-nome-e-valor-no-proximo-ano-entenda-os-motivos-fdr-terra\/"},"modified":"2022-10-10T01:07:09","modified_gmt":"2022-10-10T04:07:09","slug":"auxilio-brasil-pode-mudar-de-nome-e-valor-no-proximo-ano-entenda-os-motivos-fdr-terra","status":"publish","type":"post","link":"https:\/\/webradio2.dimariostreamhost.com\/site\/auxilio-brasil-pode-mudar-de-nome-e-valor-no-proximo-ano-entenda-os-motivos-fdr-terra\/","title":{"rendered":"AUX\u00cdLIO BRASIL pode mudar de nome e VALOR no pr\u00f3ximo ano. Entenda os motivos &#8211; FDR &#8211; Terra"},"content":{"rendered":"<p><span style=\"font-weight: 400\">Seria o <\/span><b>Aux\u00edlio Brasil<\/b> <b><i>&#8220;repaginado e melhorado&#8221;<\/i><\/b><span style=\"font-weight: 400\"> em <\/span><b>2023<\/b><span style=\"font-weight: 400\">, da mesma forma como <\/span><b>Jair Bolsonaro<\/b><span style=\"font-weight: 400\"> fez com o<\/span><b> Bolsa Fam\u00edlia<\/b><span style=\"font-weight: 400\">? A <\/span><b>C\u00e2mara dos Deputados<\/b><span style=\"font-weight: 400\"> avalia um <\/span><b>Projeto de Lei (PL) <\/b><span style=\"font-weight: 400\">que pretende acabar com a atual transfer\u00eancia de renda em <\/span><b>dezembro de 2022<\/b><span style=\"font-weight: 400\">.<\/span><br \/><span style=\"font-weight: 400\">O <\/span><b>PL n\u00ba 2315, de 2022<\/b><span style=\"font-weight: 400\">, prev\u00ea a concess\u00e3o do <\/span><a href=\"https:\/\/fdr.com.br\/direitos-beneficios\/\"><b>Aux\u00edlio Brasil <\/b><\/a><span style=\"font-weight: 400\">com<\/span><b> novo nome e valor em 2023<\/b><span style=\"font-weight: 400\">. O novo programa, intitulado de <\/span><b><a href=\"https:\/\/fdr.com.br\/direitos-beneficios\/bolsa-familia\/\">Mais Bolsa Fam\u00edlia<\/a>, <\/b><span style=\"font-weight: 400\">pagaria a parcela m\u00ednima de <\/span><b>R$ 600<\/b><span style=\"font-weight: 400\"> a partir de<\/span><b> janeiro do ano que vem<\/b><span style=\"font-weight: 400\">. O p\u00fablico-alvo seria o mesmo, <\/span><b>brasileiros em situa\u00e7\u00e3o de vulnerabilidade social<\/b><span style=\"font-weight: 400\">.\u00a0<\/span><br \/><span style=\"font-weight: 400\">O <\/span><b>deputado Alencar Santana<\/b><span style=\"font-weight: 400\">, <\/span><b>autor do<\/b> <b>PL <\/b><span style=\"font-weight: 400\">que pretende acabar com o <\/span><a href=\"https:\/\/fdr.com.br\/direitos-beneficios\/auxilio-brasil\/\"><b>Aux\u00edlio Brasil<\/b><\/a><span style=\"font-weight: 400\">, em parceria com outros <\/span><b>34 parlamentares petistas<\/b><span style=\"font-weight: 400\">, ressaltou como o atual programa foi amplamente tem sido defasado pelo<\/span><b> Governo Bolsonaro, <\/b><span style=\"font-weight: 400\">que o tem usado exclusivamente como <\/span><b>estrat\u00e9gia pol\u00edtica para reelei\u00e7\u00e3o<\/b><span style=\"font-weight: 400\">.\u00a0<\/span><br \/><i><span style=\"font-weight: 400\">\u201cAtualmente, mais de 125 milh\u00f5es de pessoas n\u00e3o t\u00eam comida garantida todo dia, nem em quantidade, muito menos em qualidade. Delas, 33 milh\u00f5es enfrentam realidade ainda pior: passam fome\u201d, ponderou o deputado.\u00a0<\/span><\/i><br \/><span style=\"font-weight: 400\">Entretanto, vale lembrar que <\/span><b>a legisla\u00e7\u00e3o eleitoral impede a aprova\u00e7\u00e3o de medidas sociais em ano de elei\u00e7\u00f5es<\/b><span style=\"font-weight: 400\">. A exce\u00e7\u00e3o ficou por conta da <\/span><b>PEC dos Benef\u00edcios<\/b><span style=\"font-weight: 400\">, que prev\u00ea o <\/span><b><a href=\"https:\/\/fdr.com.br\/2022\/10\/07\/fim-do-auxilio-brasil-camara-propoe-a-criacao-de-um-novo-programa-de-transferencia-de-renda\/\">Aux\u00edlio Brasil<\/a> de R$ 600 <\/b><span style=\"font-weight: 400\">durante <\/span><b>cinco meses<\/b><span style=\"font-weight: 400\">, mas para que pudesse ser aprovada, foi preciso publicar um <\/span><b>decreto de calamidade p\u00fablica<\/b><span style=\"font-weight: 400\">.\u00a0<\/span><br \/><span style=\"font-weight: 400\">Tamb\u00e9m \u00e9 importante ressaltar que, qualquer iniciativa social deve ser prevista pelo<\/span><b> Projeto de Lei Or\u00e7ament\u00e1ria Anual (PLOA)<\/b><span style=\"font-weight: 400\">. Portanto, n\u00e3o h\u00e1 ind\u00edcios de que o novo<\/span><b> Mais Bolsa Fam\u00edlia<\/b><span style=\"font-weight: 400\"> seja efetivado em um futuro pr\u00f3ximo.\u00a0<\/span><\/p>\n<h3 class=\"crp-list-title\"><strong><\/strong><\/h3>\n<ul class=\"crp-list\">\n<li class=\"crp-list-item crp-list-item-image-left crp-list-item-has-image\">\n<div class=\"crp-list-item-image\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/07\/auxilio-brasil-em-outubro-listamos-tudo-que-voce-precisa-saber-sobre-as-mudancas-no-projeto\/\"><img decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"59\" src=\"\/\/www.w3.org\/2000\/svg'%20viewBox='0%200%20105%2059'%3E%3C\/svg%3E\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"AUX\u00cdLIO BRASIL em outubro: listamos tudo que voc\u00ea precisa saber sobre as mudan\u00e7as no projeto\" data-lazy-srcset=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-22.jpg 1200w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-22-300x169.jpg 300w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-22-750x423.jpg 750w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-22-768x433.jpg 768w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-22-150x85.jpg 150w\" data-lazy-sizes=\"(max-width: 105px) 100vw, 105px\" data-lazy-src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-22.jpg\" \/><img decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"59\" src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-22.jpg\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"AUX\u00cdLIO BRASIL em outubro: listamos tudo que voc\u00ea precisa saber sobre as mudan\u00e7as no projeto\" \/><\/a><\/div>\n<div class=\"crp-list-item-title\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/07\/auxilio-brasil-em-outubro-listamos-tudo-que-voce-precisa-saber-sobre-as-mudancas-no-projeto\/\">AUX\u00cdLIO BRASIL em outubro: listamos tudo que voc\u00ea precisa saber sobre as mudan\u00e7as no projeto<\/a><\/div>\n<\/li>\n<li class=\"crp-list-item crp-list-item-image-left crp-list-item-has-image\">\n<div class=\"crp-list-item-image\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/07\/fim-do-auxilio-brasil-camara-propoe-a-criacao-de-um-novo-programa-de-transferencia-de-renda\/\"><img decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"59\" src=\"\/\/www.w3.org\/2000\/svg'%20viewBox='0%200%20105%2059'%3E%3C\/svg%3E\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"Fim do AUX\u00cdLIO BRASIL? C\u00e2mara prop\u00f5e a cria\u00e7\u00e3o de um novo programa de transfer\u00eancia de renda\" data-lazy-srcset=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-23.jpg 1200w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-23-300x169.jpg 300w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-23-750x423.jpg 750w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-23-768x433.jpg 768w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-23-150x85.jpg 150w\" data-lazy-sizes=\"(max-width: 105px) 100vw, 105px\" data-lazy-src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-23.jpg\" \/><img loading=\"lazy\" decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"59\" src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-23.jpg\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"Fim do AUX\u00cdLIO BRASIL? C\u00e2mara prop\u00f5e a cria\u00e7\u00e3o de um novo programa de transfer\u00eancia de renda\" loading=\"lazy\" \/><\/a><\/div>\n<div class=\"crp-list-item-title\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/07\/fim-do-auxilio-brasil-camara-propoe-a-criacao-de-um-novo-programa-de-transferencia-de-renda\/\">Fim do AUX\u00cdLIO BRASIL? C\u00e2mara prop\u00f5e a cria\u00e7\u00e3o de um novo programa de transfer\u00eancia de renda<\/a><\/div>\n<\/li>\n<li class=\"crp-list-item crp-list-item-image-left crp-list-item-has-image\">\n<div class=\"crp-list-item-image\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/07\/quem-tera-direito-a-antecipacao-do-auxilio-brasil-consulte-a-lista-de-segurados\/\"><img loading=\"lazy\" decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"70\" src=\"\/\/www.w3.org\/2000\/svg'%20viewBox='0%200%20105%2070'%3E%3C\/svg%3E\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"Quem ter\u00e1 direito a antecipa\u00e7\u00e3o do AUX\u00cdLIO BRASIL? Consulte a lista de segurados\" data-lazy-srcset=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/09\/bc020822031-21462072.jpg 1224w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/09\/bc020822031-21462072-300x200.jpg 300w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/09\/bc020822031-21462072-750x500.jpg 750w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/09\/bc020822031-21462072-768x512.jpg 768w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/09\/bc020822031-21462072-150x100.jpg 150w\" data-lazy-sizes=\"(max-width: 105px) 100vw, 105px\" data-lazy-src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/09\/bc020822031-21462072.jpg\" \/><img loading=\"lazy\" decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"70\" src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/09\/bc020822031-21462072.jpg\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"Quem ter\u00e1 direito a antecipa\u00e7\u00e3o do AUX\u00cdLIO BRASIL? Consulte a lista de segurados\" loading=\"lazy\" \/><\/a><\/div>\n<div class=\"crp-list-item-title\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/07\/quem-tera-direito-a-antecipacao-do-auxilio-brasil-consulte-a-lista-de-segurados\/\">Quem ter\u00e1 direito a antecipa\u00e7\u00e3o do AUX\u00cdLIO BRASIL? Consulte a lista de segurados<\/a><\/div>\n<\/li>\n<\/ul>\n<p><span style=\"font-weight: 400\">Quando lan\u00e7ado <\/span><b>h\u00e1 cerca de um ano atr\u00e1s<\/b><span style=\"font-weight: 400\">, o <\/span><b>Aux\u00edlio Brasil<\/b><span style=\"font-weight: 400\"> pagava o <\/span><b>valor m\u00e9dio de R$ 217,18<\/b><span style=\"font-weight: 400\">. Em<\/span><b> maio deste ano<\/b><span style=\"font-weight: 400\">,<\/span><b> foi fixada a quantia de R$ 400<\/b><span style=\"font-weight: 400\"> como o m\u00ednimo a ser recebido por cada benefici\u00e1rio.\u00a0<\/span><br \/><span style=\"font-weight: 400\">Passado pouco tempo, foi promulgada a <\/span><b>PEC dos Benef\u00edcios<\/b><span style=\"font-weight: 400\">, que prev\u00ea o<\/span><b> Aux\u00edlio Brasil<\/b><span style=\"font-weight: 400\"> de <\/span><b>R$ 600<\/b><span style=\"font-weight: 400\">. No entanto, <\/span><b>o texto tem car\u00e1ter tempor\u00e1rio<\/b><span style=\"font-weight: 400\">, com apenas <\/span><b>cinco meses de dura\u00e7\u00e3o<\/b><span style=\"font-weight: 400\">, cuja validade terminar\u00e1 em <\/span><b>dezembro de 2022<\/b><span style=\"font-weight: 400\">.\u00a0<\/span><br \/><span style=\"font-weight: 400\">Este ser\u00e1 o<\/span><b> \u00faltimo m\u00eas <\/b><span style=\"font-weight: 400\">em que o <\/span><b>Aux\u00edlio Brasil <\/b><span style=\"font-weight: 400\">pagar\u00e1 a parcela de<\/span><b> R$ 600<\/b><span style=\"font-weight: 400\">. A partir de <\/span><b>janeiro de 2022<\/b><span style=\"font-weight: 400\">, o programa volta a pagar a parcela fixa de <\/span><b>R$ 400<\/b><span style=\"font-weight: 400\">, a mesma prevista no <\/span><b>Or\u00e7amento de 2023<\/b><span style=\"font-weight: 400\">.\u00a0<\/span><br \/><span style=\"font-weight: 400\">Este \u00e9 um dos principais pontos que o novo texto em tr\u00e2mite pretende mudar. A inten\u00e7\u00e3o \u00e9 que, assim como as promessas feitas pelos presidenci\u00e1veis, que <\/span><b>o valor de R$ 600 seja mantido no pr\u00f3ximo ano<\/b><span style=\"font-weight: 400\">.<\/span><br \/>Voc\u00ea pode ficar a par das <strong>melhores not\u00edcias financeiras<\/strong> e atualizado dos seus direitos com apenas uma coisa: <strong>o seu email!<\/strong><br \/>Plataforma voltada para levar assuntos relacionados a economia popular da forma que deve ser: simples, \u00e1gil e confi\u00e1vel.<br \/>FDR\u00ae &#8211; Todos os textos s\u00e3o de propriedade intelectual deste site. Reprodu\u00e7\u00e3o n\u00e3o permitida.<br \/>FDR n\u00e3o realiza transa\u00e7\u00f5es financeiras de nenhuma monta ou tipo. O site atua como ve\u00edculo de informa\u00e7\u00e3o, provendo conte\u00fado informativo e relevante para a popula\u00e7\u00e3o em geral, muitas vezes marginalizada pelos servi\u00e7os banc\u00e1rios e grandes corpora\u00e7\u00f5es. As informa\u00e7\u00f5es aqui publicadas s\u00e3o id\u00f4neas e independentes.<\/p>\n<p><a href=\"https:\/\/fdr.com.br\/2022\/10\/09\/auxilio-brasil-pode-mudar-de-nome-e-valor-no-proximo-ano-entenda-os-motivos\/\">source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seria o Aux\u00edlio Brasil &#8220;repaginado e melhorado&#8221; em 2023, da mesma forma como Jair Bolsonaro fez com o Bolsa Fam\u00edlia? A C\u00e2mara dos Deputados avalia um Projeto de Lei (PL) que pretende acabar com a atual transfer\u00eancia de renda em dezembro de 2022.O PL n\u00ba 2315, de 2022, prev\u00ea a concess\u00e3o do Aux\u00edlio Brasil com [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":868,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/867"}],"collection":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/comments?post=867"}],"version-history":[{"count":0,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/867\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media\/868"}],"wp:attachment":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media?parent=867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/categories?post=867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/tags?post=867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}