{"id":901,"date":"2022-10-13T09:53:21","date_gmt":"2022-10-13T12:53:21","guid":{"rendered":"https:\/\/radio1.webunitystudio.site\/em-clima-de-revanche-brasil-vence-italia-no-mundial-de-volei-feminino-agencia-brasil\/"},"modified":"2022-10-13T09:53:21","modified_gmt":"2022-10-13T12:53:21","slug":"em-clima-de-revanche-brasil-vence-italia-no-mundial-de-volei-feminino-agencia-brasil","status":"publish","type":"post","link":"https:\/\/webradio2.dimariostreamhost.com\/site\/em-clima-de-revanche-brasil-vence-italia-no-mundial-de-volei-feminino-agencia-brasil\/","title":{"rendered":"Em clima de revanche, Brasil vence It\u00e1lia no Mundial de V\u00f4lei Feminino &#8211; Ag\u00eancia Brasil"},"content":{"rendered":"<p><strong>Ex.<\/strong>Sa\u00fade, Presidente, Governo <br \/>A sele\u00e7\u00e3o brasileira levou a melhor sobre a It\u00e1lia, uma das favoritas ao t\u00edtulo do Mundial de V\u00f4lei Feminino. A partida de abertura da segunda rodada da competi\u00e7\u00e3o, em Roterd\u00e3 (Holanda), teve clima de revanche \u2013 o Brasil <a href=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2022-07\/volei-italia-supera-brasil-e-leva-titulo-inedito-na-liga-das-nacoes\">perdeu para as advers\u00e1rias o t\u00edtulo da Liga das Na\u00e7\u00f5es<\/a> em julho. \u00a0Mas hoje a hist\u00f3ria foi outra: as brasileiras n\u00e3o s\u00f3 ganharam por 3 sets a 2 (\u00a025\/20, 22\/25, 22\/25, 25\/21 e 17\/15), como quebraram a invencibilidade das italianas no Mundial.<img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.png?id=1486364&amp;o=node\" style=\"width:1px;height:1px\" \/><img decoding=\"async\" src=\"https:\/\/agenciabrasil.ebc.com.br\/ebc.gif?id=1486364&amp;o=node\" style=\"width:1px;height:1px\" \/><br \/>A sele\u00e7\u00e3o comandada por Jos\u00e9 Roberto Guimar\u00e3es volta \u00e0 quadra \u00e0s 11h (hor\u00e1rio de Bras\u00edlia) desta quinta\u00a0(6) contra Porto Rico, no segundo jogo pelo Grupo E. Bicampe\u00e3 ol\u00edmpica, a sele\u00e7\u00e3o busca o t\u00edtulo in\u00e9dito do Mundial.<br \/>\u00c9 VIT\u00d3\u00d3\u00d3RIA!! \ud83c\udfd0\ud83c\udfd0\ud83c\udfd0<\/p>\n<p> As minhas meninas s\u00e3o gigantes, t\u00e1?!<\/p>\n<p> \ud83c\udde7\ud83c\uddf7 3 x 2 \ud83c\uddee\ud83c\uddf9<br \/> (25\/20, 22\/25, 22\/25, 25\/21 e 17\/15)<\/p>\n<p> Respeitem a SELE\u00c7\u00c3O BRASILEIRA! \ud83d\ude0e <a href=\"https:\/\/t.co\/iZuAY30iVw\">pic.twitter.com\/iZuAY30iVw<\/a><br \/>\u201cFiquei muito feliz com o resultado e o comportamento da equipe. Passamos por muitas adversidades durante o jogo e conseguimos ser eficientes nas horas decisivas. A diferen\u00e7a do jogo foi o n\u00famero de erros. O sistema defensivo hoje funcionou melhor e \u00e9 muito dif\u00edcil parar a Egonu. O time teve uma lucidez muito grande na marca\u00e7\u00e3o do bloqueio e no sistema defensivo. O nosso saque ainda precisa melhorar. Ganhar da It\u00e1lia foi muito importante ainda mais depois da nossa derrota para o Jap\u00e3o. O campeonato est\u00e1 aberto e temos que buscar a melhor classifica\u00e7\u00e3o poss\u00edvel\u201d, disse o treinador\u00a0Z\u00e9 Roberto, em depoimento \u00e0 Confedera\u00e7\u00e3o Brasileira de Voleibol (CBV).\u00a0\u00a0<br \/>\ud83d\udea8LIVE NOW ON VBTV!<\/p>\n<p> World Champs Pool Play: Serbia \ud83c\uddf7\ud83c\uddf8 \ud83c\udd9a \ud83c\uddf5\ud83c\uddf1 Poland<\/p>\n<p> \ud83d\udcfa Watch it on <a href=\"https:\/\/t.co\/Rb6x7tMKiz\">https:\/\/t.co\/Rb6x7tMKiz<\/a>.<\/p>\n<p> \u23f0 Sep 23 &#8211; Oct 15 schedule: <a href=\"https:\/\/t.co\/lLS0cjocfI\">https:\/\/t.co\/lLS0cjocfI<\/a><\/p>\n<p> \u26a1\ufe0f <a href=\"https:\/\/twitter.com\/hashtag\/Electrifying2022?src=hash&amp;ref_src=twsrc%5Etfw\">#Electrifying2022<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Volleyball?src=hash&amp;ref_src=twsrc%5Etfw\">#Volleyball<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/WWCH2022?src=hash&amp;ref_src=twsrc%5Etfw\">#WWCH2022<\/a> <a href=\"https:\/\/t.co\/jarkjup38w\">pic.twitter.com\/jarkjup38w<\/a><br \/>Quem brilhou \u00e0 frente da equipe nacional foi a ponteira e capit\u00e3 Gabi, que anotou 30 pontos, e a central Carol, com 14. Do lado italiano, a oposta Paola Egonu somou 37 pontos.<br \/>\u201cO diferencial da nossa equipe \u00e9 o time. Quando jogamos com essa alegria, dando confian\u00e7a uma para outra, com atitude \u00e9 dif\u00edcil jogar contra a nossa equipe. Sabemos que jogamos no conjunto, as meninas me deram for\u00e7a o tempo todo. Se acreditarmos ponto a ponto podemos jogar de igual para igual contra qualquer um dos times. Estamos focadas na postura e atitude. Foi um resultado muito importante contra uma das equipes favoritas da competi\u00e7\u00e3o. A caminhada \u00e9 muito longa e j\u00e1 vamos pensar em Porto Rico&#8221;, completou a capit\u00e3 Gabi.\u00a0<br \/>O Brasil disputa a segunda fase do Mundial no Grupo E com outras sete na\u00e7\u00f5es. No Grupo F est\u00e3o mais oito equipes. Nesta etapa do Mundial as na\u00e7\u00f5es n\u00e3o repetem os mesmos confrontos da primeira fase, ou seja, o Brasil n\u00e3o ter\u00e1 mais de encarar Jap\u00e3o, China e Argentina. Avan\u00e7am \u00e0s quartas de final as quatro sele\u00e7\u00f5es primeiras colocadas em cada chave. \u00a0<br \/>Phase 2 begins TODAY \ud83e\udd2f!<\/p>\n<p> 16 teams are in Phase 2 &amp; divided into two pools (E &amp;F). Take note all results from Phase 1 are carried over to Phase 2.<\/p>\n<p> \ud83d\udcfa Watch the matches LIVE ON VBTV.<\/p>\n<p> \u27a1\ufe0f Phase 2 EXPLANATION: <a href=\"https:\/\/t.co\/nIHn0IZ9vj\">https:\/\/t.co\/nIHn0IZ9vj<\/a><\/p>\n<p> \u26a1\ufe0f <a href=\"https:\/\/twitter.com\/hashtag\/Electrifying2022?src=hash&amp;ref_src=twsrc%5Etfw\">#Electrifying2022<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/Volleyball?src=hash&amp;ref_src=twsrc%5Etfw\">#Volleyball<\/a> <a href=\"https:\/\/twitter.com\/hashtag\/WWCH2022?src=hash&amp;ref_src=twsrc%5Etfw\">#WWCH2022<\/a> <a href=\"https:\/\/t.co\/JIzur56wx7\">pic.twitter.com\/JIzur56wx7<\/a><br \/>06.10 (QUINTA-FEIRA)\u00a0\u2013 Brasil x Porto Rico, \u00e0s 11h (hor\u00e1rio de Bras\u00edlia)<br \/> 07.10 (SEXTA-FEIRA)\u00a0\u2013 Brasil x Holanda, \u00e0s 15h15 (hor\u00e1rio de Bras\u00edlia)<br \/> 08.10 (S\u00c1BADO)\u00a0\u2013 Brasil x B\u00e9lgica, \u00e0s 12h (hor\u00e1rio de Bras\u00edlia)<br \/><em>* Texto atualizado \u00e0s 18h01\u00a0para acr\u00e9scimo de depoimentos de Jos\u00e9 Roberto Guimar\u00e3es e Gabi, e altera\u00e7\u00e3o da data do pr\u00f3ximo duelo da sele\u00e7\u00e3o brasileira.<\/em><br \/>                                                 Edi\u00e7\u00e3o:   Cl\u00e1udia Soares Rodrigues                    <br \/>Entre os alvos da opera\u00e7\u00e3o figura um casal de empres\u00e1rios que vive h\u00e1 cinco anos no Rio de Janeiro e que tem uma vida de luxo. Outro casal transportava armas.<br \/>&#8220;Hoje, esses pre\u00e7os s\u00e3o alt\u00edssimos; poder\u00edamos facilmente regul\u00e1-los em um n\u00edvel normal de mercado, sem conota\u00e7\u00f5es pol\u00edticas&#8221;, disse o presidente russo.<br \/>Pesquisadores defendem\u00a0necessidade de lideres mundiais se alinharem em\u00a0acordo ambicioso na C\u00fapula\u00a0da\u00a0Biodiversidade, em dezembro no Canad\u00e1.<br \/>Candidatos ter\u00e3o agenda no Nordeste e no Sudeste. O segundo turno da elei\u00e7\u00e3o ser\u00e1 no dia 30 de outubro.<br \/>Durante 90 dias, a contar desta quinta-feira, os militares atuar\u00e3o\u00a0nas atividades e nos servi\u00e7os imprescind\u00edveis \u00e0 preserva\u00e7\u00e3o da ordem p\u00fablica, na seguran\u00e7a das pessoas e prote\u00e7\u00e3o do patrim\u00f4nio.<br \/>Governador regional de Kiev, Oleksiy Kuleba, pediu \u00e0s pessoas que se mantenham nos abrigos at\u00e9 que as sirenes de alarme deixem de soar. Infraestruturas importantes foram atingidas.<br \/>As seis dezenas ser\u00e3o sorteadas, a partir das 20h, hor\u00e1rio de Bras\u00edlia, no Espa\u00e7o da Sorte, localizado na Avenida Paulista,\u00a0na cidade de S\u00e3o Paulo. A\u00a0aposta simples\u00a0custa R$ 4,50.<br \/>Objetivo foi aumentar a efici\u00eancia e o poder de combate\u00a0dos m\u00edsseis de cruzeiro, enviados ao Ex\u00e9rcito Popular da Coreia &#8220;para opera\u00e7\u00e3o de armas nucleares t\u00e1ticas&#8221;.<br \/>Mostra ocorre paralelamente ao Congresso Mundial de Cardiologia, que tamb\u00e9m come\u00e7a hoje e vai at\u00e9 s\u00e1bado (15) no Rio.<br \/>Emenda constitucional liberou a inclus\u00e3o de 2,2 milh\u00f5es de fam\u00edlias no Aux\u00edlio Brasil. Com isso, o total atendido pelo programa subiu para 20,65 milh\u00f5es.<br \/>Conhe\u00e7a nossos aplicativos nas lojas online da iTunes e Google<\/p>\n<p><a href=\"https:\/\/agenciabrasil.ebc.com.br\/esportes\/noticia\/2022-10\/em-clima-de-revanche-brasil-vence-italia-no-mundial-de-volei-feminino\">source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ex.Sa\u00fade, Presidente, Governo A sele\u00e7\u00e3o brasileira levou a melhor sobre a It\u00e1lia, uma das favoritas ao t\u00edtulo do Mundial de V\u00f4lei Feminino. A partida de abertura da segunda rodada da competi\u00e7\u00e3o, em Roterd\u00e3 (Holanda), teve clima de revanche \u2013 o Brasil perdeu para as advers\u00e1rias o t\u00edtulo da Liga das Na\u00e7\u00f5es em julho. \u00a0Mas hoje [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":902,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/901"}],"collection":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/comments?post=901"}],"version-history":[{"count":0,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/901\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media\/902"}],"wp:attachment":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media?parent=901"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/categories?post=901"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/tags?post=901"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}