{"id":917,"date":"2022-10-14T22:43:12","date_gmt":"2022-10-15T01:43:12","guid":{"rendered":"https:\/\/radio1.webunitystudio.site\/pousa-no-brasil-pela-primeira-vez-o-mais-novo-aviao-boeing-747-do-mundo-aeroin\/"},"modified":"2022-10-14T22:43:12","modified_gmt":"2022-10-15T01:43:12","slug":"pousa-no-brasil-pela-primeira-vez-o-mais-novo-aviao-boeing-747-do-mundo-aeroin","status":"publish","type":"post","link":"https:\/\/webradio2.dimariostreamhost.com\/site\/pousa-no-brasil-pela-primeira-vez-o-mais-novo-aviao-boeing-747-do-mundo-aeroin\/","title":{"rendered":"Pousa no Brasil pela primeira vez o mais novo avi\u00e3o Boeing 747 do mundo &#8211; AEROIN"},"content":{"rendered":"<p>H\u00e1 pouco mais de uma semana, saiu da f\u00e1brica no dia 3 de outubro e foi entregue \u00e0 companhia a\u00e9rea norte-americana Atlas Air o mais novo avi\u00e3o Boeing 747 do mundo, um equipamento do modelo 747-8F (cargueiro) e registrado sob a matr\u00edcula N861GT.<br \/>Como <a href=\"https:\/\/aeroin.net\/entra-em-operacao-o-antepenultimo-boeing-747-da-historia-e-ele-pode-vir-ao-brasil-acompanhe\/\" target=\"_blank\" rel=\"noreferrer noopener\">mostrado pelo AEROIN<\/a>, naquele dia o Jumbo Jet partiu para Miami, deixando para tr\u00e1s na linha de produ\u00e7\u00e3o os \u00faltimos dois avi\u00f5es da fam\u00edlia 747 a serem produzidos na hist\u00f3ria. E tendo voado a esse destino, um grande hub de liga\u00e7\u00f5es a\u00e9reas cargueiras com a Am\u00e9rica Latina, a expectativa era de que logo o ic\u00f4nico quadrijato seria visto no Brasil, um grande mercado da Atlas Air.<br \/>De fato, o 747-8F n\u00e3o tardou a vir, tornando o Brasil seu primeiro destino na Am\u00e9rica Latina desde que come\u00e7ou os voos comerciais. Ap\u00f3s a ida a Miami no dia 3, o Jumbo partiu de l\u00e1 no dia 8 rumo a Hong Kong, na China, e de l\u00e1 iniciou o retorno, chegando ao Aeroporto Internacional de S\u00e3o Paulo, em Guarulhos, nessa manh\u00e3 de sexta-feira, 14 de outubro, ap\u00f3s escalas em Anchorage e Miami.<br \/>O hist\u00f3rico de voo captado pela plataforma RadarBox mostra que o mais novo Jumbo Jet do mundo chegou ao Brasil \u00e0s 08h05 da manh\u00e3, conforme foi poss\u00edvel ver atrav\u00e9s das c\u00e2meras que transmitem ao vivo o movimento do aeroporto paulista.<br \/>A programa\u00e7\u00e3o de voos aprovada para Atlas Air indica pouso \u00e0s 06h35 e decolagem \u00e0s 08h45, portanto, como a chegada ocorreu com atraso de uma hora e meia, a partida tamb\u00e9m deve ser atrasada.<br \/>O v\u00eddeo a seguir mostra a c\u00e2mera ao vivo do canal Golf Oscar Romeo em Guarulhos, para que se possa acompanhar a decolagem:<br \/><strong>Atualiza\u00e7\u00e3o<\/strong>: a partida do Jumbo aconteceu \u00e0s 10h30 e pode ser vista na grava\u00e7\u00e3o a seguir.<br \/>A Atlas Air opera regularmente ao vivo com avi\u00f5es Boeing 777F, 747-400F e 747-8F, para S\u00e3o Paulo\/Guarulhos, Campinas\/Viracopos e Manaus.<\/p>\n<p><a href=\"https:\/\/aeroin.net\/pousa-no-brasil-pela-primeira-vez-o-mais-novo-aviao-boeing-747-do-mundo\/\">source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>H\u00e1 pouco mais de uma semana, saiu da f\u00e1brica no dia 3 de outubro e foi entregue \u00e0 companhia a\u00e9rea norte-americana Atlas Air o mais novo avi\u00e3o Boeing 747 do mundo, um equipamento do modelo 747-8F (cargueiro) e registrado sob a matr\u00edcula N861GT.Como mostrado pelo AEROIN, naquele dia o Jumbo Jet partiu para Miami, deixando [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":918,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/917"}],"collection":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/comments?post=917"}],"version-history":[{"count":0,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/917\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media\/918"}],"wp:attachment":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media?parent=917"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/categories?post=917"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/tags?post=917"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}