{"id":953,"date":"2022-10-18T02:58:51","date_gmt":"2022-10-18T05:58:51","guid":{"rendered":"https:\/\/radio1.webunitystudio.site\/pesquisa-aponta-mudanca-entre-os-eleitores-que-recebem-o-auxilio-brasil-fdr-terra\/"},"modified":"2022-10-18T02:58:51","modified_gmt":"2022-10-18T05:58:51","slug":"pesquisa-aponta-mudanca-entre-os-eleitores-que-recebem-o-auxilio-brasil-fdr-terra","status":"publish","type":"post","link":"https:\/\/webradio2.dimariostreamhost.com\/site\/pesquisa-aponta-mudanca-entre-os-eleitores-que-recebem-o-auxilio-brasil-fdr-terra\/","title":{"rendered":"Pesquisa aponta mudan\u00e7a entre os ELEITORES que recebem o AUX\u00cdLIO BRASIL &#8211; FDR &#8211; Terra"},"content":{"rendered":"<p>No dia 14 de outubro o Datafolha divulgou a sua mais recente <strong>pesquisa de inten\u00e7\u00e3o de votos<\/strong> para o segundo turno das elei\u00e7\u00f5es. Foi poss\u00edvel perceber uma <strong>mudan\u00e7a de comportamento entre os benefici\u00e1rios que recebem o Aux\u00edlio Brasil.<\/strong> Na pesquisa anterior esse p\u00fablico havia melhorado sua <strong>avalia\u00e7\u00e3o a respeito do atual presidente<\/strong>, mas nesta nova rodada essa tend\u00eancia n\u00e3o foi confirmada.<br \/>Lu\u00eds In\u00e1cio Lula da Silva (PT) e Jair Bolsonaro (PL) disputam o <strong>cargo da presid\u00eancia da Rep\u00fablica<\/strong> no pr\u00f3ximo dia 30 de outubro. At\u00e9 l\u00e1 as pesquisas de inten\u00e7\u00e3o de votos devem trazer um pequeno spoiler sobre como os eleitores v\u00e3o se comportar no domingo das elei\u00e7\u00f5es. O Datafolha mostrou que entre a <a href=\"https:\/\/fdr.com.br\/direitos-beneficios\/auxilio-brasil\/\"><strong>prefer\u00eancia dos benefici\u00e1rios do Aux\u00edlio Brasil<\/strong><\/a>, o atual presidente tem ca\u00eddo.<br \/>Na compara\u00e7\u00e3o entre o primeiro levantamento feito no dia 13 de outubro, e o segundo em 14 de outubro, foram vistas algumas diferen\u00e7as. Em um curto espa\u00e7o de tempo os \u00edndices demonstraram rea\u00e7\u00f5es distintas entre o p\u00fablico entrevistado. <strong>Lula tinha 56% da prefer\u00eancia, mas subiu para 62%<\/strong> no levantamento seguinte.<br \/>Enquanto isso, <strong>37% haviam demonstrado interesse em votar em Bolsonaro<\/strong> na pesquisa pesquisa, enquanto na <strong>pesquisa seguinte a prefer\u00eancia caiu para 33%.<\/strong> Demonstrando que enquanto Lula cresce entre os benefici\u00e1rios do Aux\u00edlio Brasil, Bolsonaro tem ca\u00eddo entre esse mesmo p\u00fablico, embora a atual gest\u00e3o tenha feito uma s\u00e9rie de investimentos no programa.<br \/>Esta camada representa 27% dos entrevistados pelo Datafolha, e s\u00e3o pessoas que afirmaram receber o Aux\u00edlio Brasil ou morar com quem recebe o benef\u00edcio em seu nome. Neste mesmo p\u00fablico, 29% avaliam que o atual governo \u00e9 \u00f3timo ou bom, contra 31% que tinha a mesma opini\u00e3o na pesquisa da semana anterior.<br \/>O governo de <strong>Jair Bolsonaro tem investido fortemente no programa Aux\u00edlio Brasil<\/strong>, e estes novos projetos t\u00eam sido vistos como um interesse em conseguir conquistar os brasileiros que vivem de baixa renda. Al\u00e9m disso, de aumentar a prefer\u00eancia do atual governo tamb\u00e9m entre as <strong>mulheres que s\u00e3o 80% das que recebem o benef\u00edcio<\/strong>, e dos <strong>nordestinos que ocupam 47% do saque do aux\u00edlio.\u00a0<\/strong><\/p>\n<h3 class=\"crp-list-title\"><strong><\/strong><\/h3>\n<ul class=\"crp-list\">\n<li class=\"crp-list-item crp-list-item-image-left crp-list-item-has-image\">\n<div class=\"crp-list-item-image\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/17\/auxilio-brasil-vitalicio-entenda-a-proposta-anunciada-por-bolsonaro-em-debate-na-band\/\"><img decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"59\" src=\"\/\/www.w3.org\/2000\/svg'%20viewBox='0%200%20105%2059'%3E%3C\/svg%3E\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"AUX\u00cdLIO BRASIL vital\u00edcio? Entenda a proposta anunciada por BOLSONARO em debate na Band\" data-lazy-srcset=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-52-1.jpg 1200w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-52-1-300x169.jpg 300w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-52-1-750x423.jpg 750w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-52-1-768x433.jpg 768w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-52-1-150x85.jpg 150w\" data-lazy-sizes=\"(max-width: 105px) 100vw, 105px\" data-lazy-src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-52-1.jpg\" \/><img decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"59\" src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-52-1.jpg\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"AUX\u00cdLIO BRASIL vital\u00edcio? Entenda a proposta anunciada por BOLSONARO em debate na Band\" \/><\/a><\/div>\n<div class=\"crp-list-item-title\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/17\/auxilio-brasil-vitalicio-entenda-a-proposta-anunciada-por-bolsonaro-em-debate-na-band\/\">AUX\u00cdLIO BRASIL vital\u00edcio? Entenda a proposta anunciada por BOLSONARO em debate na Band<\/a><\/div>\n<\/li>\n<li class=\"crp-list-item crp-list-item-image-left crp-list-item-has-image\">\n<div class=\"crp-list-item-image\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/17\/auxilio-brasil-covid-19-e-crime-veja-os-principais-pontos-do-debate-na-band\/\"><img decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"64\" src=\"\/\/www.w3.org\/2000\/svg'%20viewBox='0%200%20105%2064'%3E%3C\/svg%3E\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"ELEI\u00c7\u00d5ES 2022: saiba quais as principais diferen\u00e7as entre o governo LULA e BOLSONARO\" data-lazy-srcset=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/08\/lulabolsonaro-debate-band-4.jpg 1784w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/08\/lulabolsonaro-debate-band-4-300x182.jpg 300w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/08\/lulabolsonaro-debate-band-4-750x454.jpg 750w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/08\/lulabolsonaro-debate-band-4-768x465.jpg 768w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/08\/lulabolsonaro-debate-band-4-1536x930.jpg 1536w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/08\/lulabolsonaro-debate-band-4-150x91.jpg 150w\" data-lazy-sizes=\"(max-width: 105px) 100vw, 105px\" data-lazy-src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/08\/lulabolsonaro-debate-band-4.jpg\" \/><img loading=\"lazy\" decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"64\" src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/08\/lulabolsonaro-debate-band-4.jpg\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"ELEI\u00c7\u00d5ES 2022: saiba quais as principais diferen\u00e7as entre o governo LULA e BOLSONARO\" loading=\"lazy\" \/><\/a><\/div>\n<div class=\"crp-list-item-title\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/17\/auxilio-brasil-covid-19-e-crime-veja-os-principais-pontos-do-debate-na-band\/\">Aux\u00edlio Brasil, Covid-19 e crime. Veja os principais pontos do DEBATE na BAND<\/a><\/div>\n<\/li>\n<li class=\"crp-list-item crp-list-item-image-left crp-list-item-has-image\">\n<div class=\"crp-list-item-image\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/16\/eleicoes-2022-quem-tem-mais-chances-de-ganhar-lula-ou-bolsonaro-especialista-responde\/\"><img loading=\"lazy\" decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"59\" src=\"\/\/www.w3.org\/2000\/svg'%20viewBox='0%200%20105%2059'%3E%3C\/svg%3E\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"ELEI\u00c7\u00d5ES 2022: quem tem mais chances de ganhar, Lula ou Bolsonaro? Especialista responde\" data-lazy-srcset=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-48-1.jpg 1200w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-48-1-300x169.jpg 300w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-48-1-750x423.jpg 750w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-48-1-768x433.jpg 768w, https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-48-1-150x85.jpg 150w\" data-lazy-sizes=\"(max-width: 105px) 100vw, 105px\" data-lazy-src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-48-1.jpg\" \/><img loading=\"lazy\" decoding=\"async\" data-pin-nopin=\"true\" style=\"max-width: 105px;height: auto\" width=\"105\" height=\"59\" src=\"https:\/\/fdr.com.br\/wp-content\/uploads\/2022\/10\/Imagens-FDR-48-1.jpg\" class=\"attachment-105x75 size-105x75 wp-post-image\" alt=\"ELEI\u00c7\u00d5ES 2022: quem tem mais chances de ganhar, Lula ou Bolsonaro? Especialista responde\" loading=\"lazy\" \/><\/a><\/div>\n<div class=\"crp-list-item-title\"><a href=\"https:\/\/fdr.com.br\/2022\/10\/16\/eleicoes-2022-quem-tem-mais-chances-de-ganhar-lula-ou-bolsonaro-especialista-responde\/\">ELEI\u00c7\u00d5ES 2022: quem tem mais chances de ganhar, Lula ou Bolsonaro? Especialista responde<\/a><\/div>\n<\/li>\n<\/ul>\n<p>Desde agosto o pagamento que era de <strong>R$ 400 passou a ser de R$ 600 pelo menos at\u00e9 dezembro<\/strong> deste ano. Todos os meses <strong>mais fam\u00edlias est\u00e3o sendo inclusas<\/strong> no programa, em outubro foram pelo menos 400 mil novos inscritos. Al\u00e9m da <strong>antecipa\u00e7\u00e3o do calend\u00e1rio<\/strong> e <strong><a href=\"https:\/\/fdr.com.br\/2022\/10\/15\/duvidas-sobre-o-emprestimo-consignado-aprovado-pela-caixa-respondemos-para-voce\/\">oferta de empr\u00e9stimo consignado<\/a>.\u00a0<\/strong><br \/>Voc\u00ea pode ficar a par das <strong>melhores not\u00edcias financeiras<\/strong> e atualizado dos seus direitos com apenas uma coisa: <strong>o seu email!<\/strong><br \/>Plataforma voltada para levar assuntos relacionados a economia popular da forma que deve ser: simples, \u00e1gil e confi\u00e1vel.<br \/>FDR\u00ae &#8211; Todos os textos s\u00e3o de propriedade intelectual deste site. Reprodu\u00e7\u00e3o n\u00e3o permitida.<br \/>FDR n\u00e3o realiza transa\u00e7\u00f5es financeiras de nenhuma monta ou tipo. O site atua como ve\u00edculo de informa\u00e7\u00e3o, provendo conte\u00fado informativo e relevante para a popula\u00e7\u00e3o em geral, muitas vezes marginalizada pelos servi\u00e7os banc\u00e1rios e grandes corpora\u00e7\u00f5es. As informa\u00e7\u00f5es aqui publicadas s\u00e3o id\u00f4neas e independentes.<\/p>\n<p><a href=\"https:\/\/news.google.com\/__i\/rss\/rd\/articles\/CBMiZmh0dHBzOi8vZmRyLmNvbS5ici8yMDIyLzEwLzE3L3Blc3F1aXNhLWFwb250YS1tdWRhbmNhLWVudHJlLW9zLWVsZWl0b3Jlcy1xdWUtcmVjZWJlbS1vLWF1eGlsaW8tYnJhc2lsL9IBAA?oc=5\">source<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>No dia 14 de outubro o Datafolha divulgou a sua mais recente pesquisa de inten\u00e7\u00e3o de votos para o segundo turno das elei\u00e7\u00f5es. Foi poss\u00edvel perceber uma mudan\u00e7a de comportamento entre os benefici\u00e1rios que recebem o Aux\u00edlio Brasil. Na pesquisa anterior esse p\u00fablico havia melhorado sua avalia\u00e7\u00e3o a respeito do atual presidente, mas nesta nova [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":954,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"_links":{"self":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/953"}],"collection":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/comments?post=953"}],"version-history":[{"count":0,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/posts\/953\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media\/954"}],"wp:attachment":[{"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/media?parent=953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/categories?post=953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/webradio2.dimariostreamhost.com\/site\/wp-json\/wp\/v2\/tags?post=953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}